<div class="row" id="courses_content">            <div class="wpb_row vc_row-fluid vc_row">
                <div class="nectar-highlighted-text branch" data-style="full_text" data-exp="default" data-using-custom-color="false" data-animation-delay="false" data-color="" data-color-gradient="" style="">
                    <h3><strong>Humanities &amp; Social Sciences</strong></h3>
                </div>
                <div class='row_col_wrap_12 col span_12 dark left'>        <div class="vc_col-sm-4 wpb_column column_container vc_column_container col no-extra-padding inherit_tablet inherit_phone" data-padding-pos="all" data-has-bg-color="false" data-bg-color="" data-bg-opacity="1" data-animation="" data-delay="0">
            <div class="vc_column-inner">
                <div class="wpb_wrapper">
                    <div class="nectar-fancy-box nectar-underline content-color-000000 aspect-1-1 past-deadline" data-style="image_above_text_underline" data-border-radius="none" data-animation="" data-delay="" data-alignment="left">
                        <div class="image-wrap">
                            <div class="box-bg">

                            </div>
                        </div>

                        <div class="text">
                            <h5>Information &amp; Fake News 26-27 S1</h5>
                            <p><img loading="lazy" class="wp-image-7458 size-medium alignleft" src="https://eunice-university.eu/wp-content/uploads/2026/05/Flyer_Information-and-Fake-News-2026-2027-212x300.jpg" alt="Information &amp; Fake News 26-27 S1" ></p>
                            <p style="text-align: left"><strong>1 octubre - 31 enero, 2027</strong></p>
                            <p><strong>Applications closed</strong></p>                        </div>

                        <a href="https://eunice-university.eu/es/course/information-and-fake-news-2026-2027/" class="box-link"></a>
                    </div>
                </div> 
            </div>
        </div>

            <div class="vc_col-sm-4 wpb_column column_container vc_column_container col no-extra-padding inherit_tablet inherit_phone" data-padding-pos="all" data-has-bg-color="false" data-bg-color="" data-bg-opacity="1" data-animation="" data-delay="0">
            <div class="vc_column-inner">
                <div class="wpb_wrapper">
                    <div class="nectar-fancy-box nectar-underline content-color-000000 aspect-1-1 past-deadline" data-style="image_above_text_underline" data-border-radius="none" data-animation="" data-delay="" data-alignment="left">
                        <div class="image-wrap">
                            <div class="box-bg">

                            </div>
                        </div>

                        <div class="text">
                            <h5>BIP &#8211; Autumn School in Global Sustainable Tourism Development</h5>
                            <p><img loading="lazy" class="wp-image-7458 size-medium alignleft" src="https://eunice-university.eu/wp-content/uploads/2026/07/BIP-GLOBAL-SUSTAINABLE-TOURISM-DEVELOPMENT-1-212x300.jpg" alt="BIP &#8211; Autumn School in Global Sustainable Tourism Development" ></p>
                            <p style="text-align: left"><strong>26 octubre - 30 octubre, 2026</strong></p>
                            <p><strong>Applications closed</strong></p>                        </div>

                        <a href="https://eunice-university.eu/es/course/bip-autumn-school-in-global-sustainable-tourism-development/" class="box-link"></a>
                    </div>
                </div> 
            </div>
        </div>

            <div class="vc_col-sm-4 wpb_column column_container vc_column_container col no-extra-padding inherit_tablet inherit_phone" data-padding-pos="all" data-has-bg-color="false" data-bg-color="" data-bg-opacity="1" data-animation="" data-delay="0">
            <div class="vc_column-inner">
                <div class="wpb_wrapper">
                    <div class="nectar-fancy-box nectar-underline content-color-000000 aspect-1-1 past-deadline" data-style="image_above_text_underline" data-border-radius="none" data-animation="" data-delay="" data-alignment="left">
                        <div class="image-wrap">
                            <div class="box-bg">

                            </div>
                        </div>

                        <div class="text">
                            <h5>Sustainable and Inclusive Societies for a Better Future</h5>
                            <p><img loading="lazy" class="wp-image-7458 size-medium alignleft" src="https://eunice-university.eu/wp-content/uploads/2026/03/BIP-Sustainable-Inlcusive-Societies-212x300.jpg" alt="Sustainable and Inclusive Societies for a Better Future" ></p>
                            <p style="text-align: left"><strong>29 junio - 24 julio, 2026</strong></p>
                            <p><strong>Applications closed</strong></p>                        </div>

                        <a href="https://eunice-university.eu/es/course/sustainable-and-inclusive-societies-for-a-better-future/" class="box-link"></a>
                    </div>
                </div> 
            </div>
        </div>

    </div><div class='row_col_wrap_12 col span_12 dark left'>        <div class="vc_col-sm-4 wpb_column column_container vc_column_container col no-extra-padding inherit_tablet inherit_phone" data-padding-pos="all" data-has-bg-color="false" data-bg-color="" data-bg-opacity="1" data-animation="" data-delay="0">
            <div class="vc_column-inner">
                <div class="wpb_wrapper">
                    <div class="nectar-fancy-box nectar-underline content-color-000000 aspect-1-1 past-deadline" data-style="image_above_text_underline" data-border-radius="none" data-animation="" data-delay="" data-alignment="left">
                        <div class="image-wrap">
                            <div class="box-bg">

                            </div>
                        </div>

                        <div class="text">
                            <h5>Strengthening resilience in the times of polycrises</h5>
                            <p><img loading="lazy" class="wp-image-7458 size-medium alignleft" src="https://eunice-university.eu/wp-content/uploads/2026/02/uva-resilience-bip-flyer-cover-212x300.jpg" alt="Strengthening resilience in the times of polycrises" ></p>
                            <p style="text-align: left"><strong>1 mayo - 29 mayo, 2026</strong></p>
                            <p><strong>Applications closed</strong></p>                        </div>

                        <a href="https://eunice-university.eu/es/course/strengthening-resilience-in-the-times-of-polycrises/" class="box-link"></a>
                    </div>
                </div> 
            </div>
        </div>

            <div class="vc_col-sm-4 wpb_column column_container vc_column_container col no-extra-padding inherit_tablet inherit_phone" data-padding-pos="all" data-has-bg-color="false" data-bg-color="" data-bg-opacity="1" data-animation="" data-delay="0">
            <div class="vc_column-inner">
                <div class="wpb_wrapper">
                    <div class="nectar-fancy-box nectar-underline content-color-000000 aspect-1-1 past-deadline" data-style="image_above_text_underline" data-border-radius="none" data-animation="" data-delay="" data-alignment="left">
                        <div class="image-wrap">
                            <div class="box-bg">

                            </div>
                        </div>

                        <div class="text">
                            <h5>Communication in Sport</h5>
                            <p><img loading="lazy" class="wp-image-7458 size-medium alignleft" src="https://eunice-university.eu/wp-content/uploads/2025/07/BIP-Communicaation-in-sport-min-212x300.jpg" alt="Communication in Sport" ></p>
                            <p style="text-align: left"><strong>6 octubre - 14 noviembre, 2025</strong></p>
                            <p><strong>Applications closed</strong></p>                        </div>

                        <a href="https://eunice-university.eu/es/course/communication-in-sport/" class="box-link"></a>
                    </div>
                </div> 
            </div>
        </div>

            <div class="vc_col-sm-4 wpb_column column_container vc_column_container col no-extra-padding inherit_tablet inherit_phone" data-padding-pos="all" data-has-bg-color="false" data-bg-color="" data-bg-opacity="1" data-animation="" data-delay="0">
            <div class="vc_column-inner">
                <div class="wpb_wrapper">
                    <div class="nectar-fancy-box nectar-underline content-color-000000 aspect-1-1 past-deadline" data-style="image_above_text_underline" data-border-radius="none" data-animation="" data-delay="" data-alignment="left">
                        <div class="image-wrap">
                            <div class="box-bg">

                            </div>
                        </div>

                        <div class="text">
                            <h5>Crossing Borders: Colonial Echoes in Language, Space and Culture &#8211; Summer School</h5>
                            <p><img loading="lazy" class="wp-image-7458 size-medium alignleft" src="https://eunice-university.eu/wp-content/uploads/2025/02/Crossing-borders-flyer-212x300.jpg" alt="Crossing Borders: Colonial Echoes in Language, Space and Culture &#8211; Summer School" ></p>
                            <p style="text-align: left"><strong>30 junio - 11 julio, 2025</strong></p>
                            <p><strong>Applications closed</strong></p>                        </div>

                        <a href="https://eunice-university.eu/es/course/crossing-borders-summer-school-2025/" class="box-link"></a>
                    </div>
                </div> 
            </div>
        </div>

    </div><div class='row_col_wrap_12 col span_12 dark left'>        <div class="vc_col-sm-4 wpb_column column_container vc_column_container col no-extra-padding inherit_tablet inherit_phone" data-padding-pos="all" data-has-bg-color="false" data-bg-color="" data-bg-opacity="1" data-animation="" data-delay="0">
            <div class="vc_column-inner">
                <div class="wpb_wrapper">
                    <div class="nectar-fancy-box nectar-underline content-color-000000 aspect-1-1" data-style="image_above_text_underline" data-border-radius="none" data-animation="" data-delay="" data-alignment="left">
                        <div class="image-wrap">
                            <div class="box-bg">

                            </div>
                        </div>

                        <div class="text">
                            <h5>Inclusion and empowerment in mobility opportunities</h5>
                            <p><img loading="lazy" class="wp-image-7458 size-medium alignleft" src="https://eunice-university.eu/wp-content/uploads/2026/09/3-212x300.jpg" alt="Inclusion and empowerment in mobility opportunities" ></p>
                            <p style="text-align: left"><strong>22 octubre - 4 noviembre, 2026</strong></p>
                            <p><strong>Applications deadline: </strong></p>                        </div>

                        <a href="https://eunice-university.eu/es/course/65583-2/" class="box-link"></a>
                    </div>
                </div> 
            </div>
        </div>

    </div></div>            <div class="wpb_row vc_row-fluid vc_row">
                <div class="nectar-highlighted-text branch" data-style="full_text" data-exp="default" data-using-custom-color="false" data-animation-delay="false" data-color="" data-color-gradient="" style="">
                    <h3><strong>Health Care</strong></h3>
                </div>
                <div class='row_col_wrap_12 col span_12 dark left'>        <div class="vc_col-sm-4 wpb_column column_container vc_column_container col no-extra-padding inherit_tablet inherit_phone" data-padding-pos="all" data-has-bg-color="false" data-bg-color="" data-bg-opacity="1" data-animation="" data-delay="0">
            <div class="vc_column-inner">
                <div class="wpb_wrapper">
                    <div class="nectar-fancy-box nectar-underline content-color-000000 aspect-1-1 past-deadline" data-style="image_above_text_underline" data-border-radius="none" data-animation="" data-delay="" data-alignment="left">
                        <div class="image-wrap">
                            <div class="box-bg">

                            </div>
                        </div>

                        <div class="text">
                            <h5>Problems of Elderly Patients as an Interdisciplinary Issue Summer School</h5>
                            <p><img loading="lazy" class="wp-image-7458 size-medium alignleft" src="https://eunice-university.eu/wp-content/uploads/2026/06/elderly-patients_small-212x300.png" alt="Problems of Elderly Patients as an Interdisciplinary Issue Summer School" ></p>
                            <p style="text-align: left"><strong>7 septiembre - 11 septiembre, 2026</strong></p>
                            <p><strong>Applications closed</strong></p>                        </div>

                        <a href="https://eunice-university.eu/es/course/problems-of-elderly-patients-as-an-interdisciplinary-issue-summer-school/" class="box-link"></a>
                    </div>
                </div> 
            </div>
        </div>

            <div class="vc_col-sm-4 wpb_column column_container vc_column_container col no-extra-padding inherit_tablet inherit_phone" data-padding-pos="all" data-has-bg-color="false" data-bg-color="" data-bg-opacity="1" data-animation="" data-delay="0">
            <div class="vc_column-inner">
                <div class="wpb_wrapper">
                    <div class="nectar-fancy-box nectar-underline content-color-000000 aspect-1-1 past-deadline" data-style="image_above_text_underline" data-border-radius="none" data-animation="" data-delay="" data-alignment="left">
                        <div class="image-wrap">
                            <div class="box-bg">

                            </div>
                        </div>

                        <div class="text">
                            <h5>Physical Exercise and Sport for All: Inclusion, Health and Participation</h5>
                            <p><img loading="lazy" class="wp-image-7458 size-medium alignleft" src="https://eunice-university.eu/wp-content/uploads/2026/04/WhatsApp-Image-2026-04-27-at-09.19.07-212x300.jpeg" alt="Physical Exercise and Sport for All: Inclusion, Health and Participation" ></p>
                            <p style="text-align: left"><strong>27 abril - 10 mayo, 2026</strong></p>
                            <p><strong>Applications closed</strong></p>                        </div>

                        <a href="https://eunice-university.eu/es/course/physical-exercise-and-sport-for-all-inclusion-health-and-participation/" class="box-link"></a>
                    </div>
                </div> 
            </div>
        </div>

    </div></div>            <div class="wpb_row vc_row-fluid vc_row">
                <div class="nectar-highlighted-text branch" data-style="full_text" data-exp="default" data-using-custom-color="false" data-animation-delay="false" data-color="" data-color-gradient="" style="">
                    <h3><strong>Soft Skills &amp; Global Competences</strong></h3>
                </div>
                <div class='row_col_wrap_12 col span_12 dark left'>        <div class="vc_col-sm-4 wpb_column column_container vc_column_container col no-extra-padding inherit_tablet inherit_phone" data-padding-pos="all" data-has-bg-color="false" data-bg-color="" data-bg-opacity="1" data-animation="" data-delay="0">
            <div class="vc_column-inner">
                <div class="wpb_wrapper">
                    <div class="nectar-fancy-box nectar-underline content-color-000000 aspect-1-1 past-deadline" data-style="image_above_text_underline" data-border-radius="none" data-animation="" data-delay="" data-alignment="left">
                        <div class="image-wrap">
                            <div class="box-bg">

                            </div>
                        </div>

                        <div class="text">
                            <h5>Soft Skills Summer School</h5>
                            <p><img loading="lazy" class="wp-image-7458 size-medium alignleft" src="https://eunice-university.eu/wp-content/uploads/2026/06/soft-skills_small-212x300.png" alt="Soft Skills Summer School" ></p>
                            <p style="text-align: left"><strong>7 septiembre - 11 septiembre, 2026</strong></p>
                            <p><strong>Applications closed</strong></p>                        </div>

                        <a href="https://eunice-university.eu/es/course/soft-skills-summer-school/" class="box-link"></a>
                    </div>
                </div> 
            </div>
        </div>

            <div class="vc_col-sm-4 wpb_column column_container vc_column_container col no-extra-padding inherit_tablet inherit_phone" data-padding-pos="all" data-has-bg-color="false" data-bg-color="" data-bg-opacity="1" data-animation="" data-delay="0">
            <div class="vc_column-inner">
                <div class="wpb_wrapper">
                    <div class="nectar-fancy-box nectar-underline content-color-000000 aspect-1-1 past-deadline" data-style="image_above_text_underline" data-border-radius="none" data-animation="" data-delay="" data-alignment="left">
                        <div class="image-wrap">
                            <div class="box-bg">

                            </div>
                        </div>

                        <div class="text">
                            <h5>Soft Skills</h5>
                            <p><img loading="lazy" class="wp-image-7458 size-medium alignleft" src="https://eunice-university.eu/wp-content/uploads/2026/04/soft-skills_flyer_small-212x300.png" alt="Soft Skills" ></p>
                            <p style="text-align: left"><strong>6 julio - 10 julio, 2026</strong></p>
                            <p><strong>Applications closed</strong></p>                        </div>

                        <a href="https://eunice-university.eu/es/course/soft-skills/" class="box-link"></a>
                    </div>
                </div> 
            </div>
        </div>

            <div class="vc_col-sm-4 wpb_column column_container vc_column_container col no-extra-padding inherit_tablet inherit_phone" data-padding-pos="all" data-has-bg-color="false" data-bg-color="" data-bg-opacity="1" data-animation="" data-delay="0">
            <div class="vc_column-inner">
                <div class="wpb_wrapper">
                    <div class="nectar-fancy-box nectar-underline content-color-000000 aspect-1-1 past-deadline" data-style="image_above_text_underline" data-border-radius="none" data-animation="" data-delay="" data-alignment="left">
                        <div class="image-wrap">
                            <div class="box-bg">

                            </div>
                        </div>

                        <div class="text">
                            <h5>Global Studies in a Changing World &#8211; Challenges and Solutions 25-26 S2</h5>
                            <p><img loading="lazy" class="wp-image-7458 size-medium alignleft" src="https://eunice-university.eu/wp-content/uploads/2026/03/BIP-Global-2026-Flyer-side-A-212x300.jpg" alt="Global Studies in a Changing World &#8211; Challenges and Solutions 25-26 S2" ></p>
                            <p style="text-align: left"><strong>1 junio - 10 julio, 2026</strong></p>
                            <p><strong>Applications closed</strong></p>                        </div>

                        <a href="https://eunice-university.eu/es/course/global-studies-in-a-changing-world-challenges-and-solutions-25-26-s2/" class="box-link"></a>
                    </div>
                </div> 
            </div>
        </div>

    </div><div class='row_col_wrap_12 col span_12 dark left'>        <div class="vc_col-sm-4 wpb_column column_container vc_column_container col no-extra-padding inherit_tablet inherit_phone" data-padding-pos="all" data-has-bg-color="false" data-bg-color="" data-bg-opacity="1" data-animation="" data-delay="0">
            <div class="vc_column-inner">
                <div class="wpb_wrapper">
                    <div class="nectar-fancy-box nectar-underline content-color-000000 aspect-1-1 past-deadline" data-style="image_above_text_underline" data-border-radius="none" data-animation="" data-delay="" data-alignment="left">
                        <div class="image-wrap">
                            <div class="box-bg">

                            </div>
                        </div>

                        <div class="text">
                            <h5>Discovering research in a European context</h5>
                            <p><img loading="lazy" class="wp-image-7458 size-medium alignleft" src="https://eunice-university.eu/wp-content/uploads/2025/10/BIP-Discovering-research-Page-pour-site-1-212x300.jpg" alt="Discovering research in a European context" ></p>
                            <p style="text-align: left"><strong>9 marzo - 20 marzo, 2026</strong></p>
                            <p><strong>Applications closed</strong></p>                        </div>

                        <a href="https://eunice-university.eu/es/course/discovering-research-in-a-european-context/" class="box-link"></a>
                    </div>
                </div> 
            </div>
        </div>

            <div class="vc_col-sm-4 wpb_column column_container vc_column_container col no-extra-padding inherit_tablet inherit_phone" data-padding-pos="all" data-has-bg-color="false" data-bg-color="" data-bg-opacity="1" data-animation="" data-delay="0">
            <div class="vc_column-inner">
                <div class="wpb_wrapper">
                    <div class="nectar-fancy-box nectar-underline content-color-000000 aspect-1-1 past-deadline" data-style="image_above_text_underline" data-border-radius="none" data-animation="" data-delay="" data-alignment="left">
                        <div class="image-wrap">
                            <div class="box-bg">

                            </div>
                        </div>

                        <div class="text">
                            <h5>Global Studies in Uncertain Times &#8211; Summer School</h5>
                            <p><img loading="lazy" class="wp-image-7458 size-medium alignleft" src="https://eunice-university.eu/wp-content/uploads/2025/03/BIP-Global-Studies-in-Uncertain-Times-Spain-2025-Flyer-side-A-212x300.jpg" alt="Global Studies in Uncertain Times &#8211; Summer School" ></p>
                            <p style="text-align: left"><strong>2 junio - 13 julio, 2025</strong></p>
                            <p><strong>Applications closed</strong></p>                        </div>

                        <a href="https://eunice-university.eu/es/course/global-studies-summer-school-2025/" class="box-link"></a>
                    </div>
                </div> 
            </div>
        </div>

            <div class="vc_col-sm-4 wpb_column column_container vc_column_container col no-extra-padding inherit_tablet inherit_phone" data-padding-pos="all" data-has-bg-color="false" data-bg-color="" data-bg-opacity="1" data-animation="" data-delay="0">
            <div class="vc_column-inner">
                <div class="wpb_wrapper">
                    <div class="nectar-fancy-box nectar-underline content-color-000000 aspect-1-1 past-deadline" data-style="image_above_text_underline" data-border-radius="none" data-animation="" data-delay="" data-alignment="left">
                        <div class="image-wrap">
                            <div class="box-bg">

                            </div>
                        </div>

                        <div class="text">
                            <h5>Intercultural Relations and Intercomprehension in Mobility and in Higher Education Institutions</h5>
                            <p><img loading="lazy" class="wp-image-7458 size-medium alignleft" src="https://eunice-university.eu/wp-content/uploads/2024/07/BIP-Brochure-1_page-0001-212x300.jpg" alt="Intercultural Relations and Intercomprehension in Mobility and in Higher Education Institutions" ></p>
                            <p style="text-align: left"><strong>2 diciembre - 7 febrero, 2025</strong></p>
                            <p><strong>Applications closed</strong></p>                        </div>

                        <a href="https://eunice-university.eu/es/course/intercultural-relations-and-intercomprehension-in-mobility-and-in-higher-education-institutions/" class="box-link"></a>
                    </div>
                </div> 
            </div>
        </div>

    </div><div class='row_col_wrap_12 col span_12 dark left'>        <div class="vc_col-sm-4 wpb_column column_container vc_column_container col no-extra-padding inherit_tablet inherit_phone" data-padding-pos="all" data-has-bg-color="false" data-bg-color="" data-bg-opacity="1" data-animation="" data-delay="0">
            <div class="vc_column-inner">
                <div class="wpb_wrapper">
                    <div class="nectar-fancy-box nectar-underline content-color-000000 aspect-1-1" data-style="image_above_text_underline" data-border-radius="none" data-animation="" data-delay="" data-alignment="left">
                        <div class="image-wrap">
                            <div class="box-bg">

                            </div>
                        </div>

                        <div class="text">
                            <h5>Inclusion and empowerment in mobility opportunities</h5>
                            <p><img loading="lazy" class="wp-image-7458 size-medium alignleft" src="https://eunice-university.eu/wp-content/uploads/2026/09/3-212x300.jpg" alt="Inclusion and empowerment in mobility opportunities" ></p>
                            <p style="text-align: left"><strong>22 octubre - 4 noviembre, 2026</strong></p>
                            <p><strong>Applications deadline: </strong></p>                        </div>

                        <a href="https://eunice-university.eu/es/course/65583-2/" class="box-link"></a>
                    </div>
                </div> 
            </div>
        </div>

    </div></div>            <div class="wpb_row vc_row-fluid vc_row">
                <div class="nectar-highlighted-text branch" data-style="full_text" data-exp="default" data-using-custom-color="false" data-animation-delay="false" data-color="" data-color-gradient="" style="">
                    <h3><strong>Sustainable Development</strong></h3>
                </div>
                <div class='row_col_wrap_12 col span_12 dark left'>        <div class="vc_col-sm-4 wpb_column column_container vc_column_container col no-extra-padding inherit_tablet inherit_phone" data-padding-pos="all" data-has-bg-color="false" data-bg-color="" data-bg-opacity="1" data-animation="" data-delay="0">
            <div class="vc_column-inner">
                <div class="wpb_wrapper">
                    <div class="nectar-fancy-box nectar-underline content-color-000000 aspect-1-1 past-deadline" data-style="image_above_text_underline" data-border-radius="none" data-animation="" data-delay="" data-alignment="left">
                        <div class="image-wrap">
                            <div class="box-bg">

                            </div>
                        </div>

                        <div class="text">
                            <h5>BIP &#8211; Autumn School in Global Sustainable Tourism Development</h5>
                            <p><img loading="lazy" class="wp-image-7458 size-medium alignleft" src="https://eunice-university.eu/wp-content/uploads/2026/07/BIP-GLOBAL-SUSTAINABLE-TOURISM-DEVELOPMENT-1-212x300.jpg" alt="BIP &#8211; Autumn School in Global Sustainable Tourism Development" ></p>
                            <p style="text-align: left"><strong>26 octubre - 30 octubre, 2026</strong></p>
                            <p><strong>Applications closed</strong></p>                        </div>

                        <a href="https://eunice-university.eu/es/course/bip-autumn-school-in-global-sustainable-tourism-development/" class="box-link"></a>
                    </div>
                </div> 
            </div>
        </div>

            <div class="vc_col-sm-4 wpb_column column_container vc_column_container col no-extra-padding inherit_tablet inherit_phone" data-padding-pos="all" data-has-bg-color="false" data-bg-color="" data-bg-opacity="1" data-animation="" data-delay="0">
            <div class="vc_column-inner">
                <div class="wpb_wrapper">
                    <div class="nectar-fancy-box nectar-underline content-color-000000 aspect-1-1 past-deadline" data-style="image_above_text_underline" data-border-radius="none" data-animation="" data-delay="" data-alignment="left">
                        <div class="image-wrap">
                            <div class="box-bg">

                            </div>
                        </div>

                        <div class="text">
                            <h5>Biomimetic Chemistry and Green Nanotechnologies &#8211; Summer School</h5>
                            <p><img loading="lazy" class="wp-image-7458 size-medium alignleft" src="https://eunice-university.eu/wp-content/uploads/2026/05/Online-courses-template-BTU-212x300.jpg" alt="Biomimetic Chemistry and Green Nanotechnologies &#8211; Summer School" ></p>
                            <p style="text-align: left"><strong>1 septiembre - 25 septiembre, 2026</strong></p>
                            <p><strong>Applications closed</strong></p>                        </div>

                        <a href="https://eunice-university.eu/es/course/biomimetic-chemistry-and-green-nanotechnologies-summer-school/" class="box-link"></a>
                    </div>
                </div> 
            </div>
        </div>

            <div class="vc_col-sm-4 wpb_column column_container vc_column_container col no-extra-padding inherit_tablet inherit_phone" data-padding-pos="all" data-has-bg-color="false" data-bg-color="" data-bg-opacity="1" data-animation="" data-delay="0">
            <div class="vc_column-inner">
                <div class="wpb_wrapper">
                    <div class="nectar-fancy-box nectar-underline content-color-000000 aspect-1-1 past-deadline" data-style="image_above_text_underline" data-border-radius="none" data-animation="" data-delay="" data-alignment="left">
                        <div class="image-wrap">
                            <div class="box-bg">

                            </div>
                        </div>

                        <div class="text">
                            <h5>The Circular Urban Turn &#8211; Towards Zero-Waste Cities and Regions 26-27 S1</h5>
                            <p><img loading="lazy" class="wp-image-7458 size-medium alignleft" src="https://eunice-university.eu/wp-content/uploads/2026/04/BIP-Circular-Urban-Turn-cover-240x300.jpg" alt="The Circular Urban Turn &#8211; Towards Zero-Waste Cities and Regions 26-27 S1" ></p>
                            <p style="text-align: left"><strong>29 mayo - 12 septiembre, 2026</strong></p>
                            <p><strong>Applications closed</strong></p>                        </div>

                        <a href="https://eunice-university.eu/es/course/summer-school-circular-urban-turn-26-27-s1/" class="box-link"></a>
                    </div>
                </div> 
            </div>
        </div>

    </div><div class='row_col_wrap_12 col span_12 dark left'>        <div class="vc_col-sm-4 wpb_column column_container vc_column_container col no-extra-padding inherit_tablet inherit_phone" data-padding-pos="all" data-has-bg-color="false" data-bg-color="" data-bg-opacity="1" data-animation="" data-delay="0">
            <div class="vc_column-inner">
                <div class="wpb_wrapper">
                    <div class="nectar-fancy-box nectar-underline content-color-000000 aspect-1-1 past-deadline" data-style="image_above_text_underline" data-border-radius="none" data-animation="" data-delay="" data-alignment="left">
                        <div class="image-wrap">
                            <div class="box-bg">

                            </div>
                        </div>

                        <div class="text">
                            <h5>Sustainable and Inclusive Societies for a Better Future</h5>
                            <p><img loading="lazy" class="wp-image-7458 size-medium alignleft" src="https://eunice-university.eu/wp-content/uploads/2026/03/BIP-Sustainable-Inlcusive-Societies-212x300.jpg" alt="Sustainable and Inclusive Societies for a Better Future" ></p>
                            <p style="text-align: left"><strong>29 junio - 24 julio, 2026</strong></p>
                            <p><strong>Applications closed</strong></p>                        </div>

                        <a href="https://eunice-university.eu/es/course/sustainable-and-inclusive-societies-for-a-better-future/" class="box-link"></a>
                    </div>
                </div> 
            </div>
        </div>

            <div class="vc_col-sm-4 wpb_column column_container vc_column_container col no-extra-padding inherit_tablet inherit_phone" data-padding-pos="all" data-has-bg-color="false" data-bg-color="" data-bg-opacity="1" data-animation="" data-delay="0">
            <div class="vc_column-inner">
                <div class="wpb_wrapper">
                    <div class="nectar-fancy-box nectar-underline content-color-000000 aspect-1-1 past-deadline" data-style="image_above_text_underline" data-border-radius="none" data-animation="" data-delay="" data-alignment="left">
                        <div class="image-wrap">
                            <div class="box-bg">

                            </div>
                        </div>

                        <div class="text">
                            <h5>Innovating Solutions: Micro-Nano Technologies and Sensors for Global Challenges &#8211; Research Summer School</h5>
                            <p><img loading="lazy" class="wp-image-7458 size-medium alignleft" src="https://eunice-university.eu/wp-content/uploads/2026/02/Flyer-BIP-on-Micro-nano-Technologies-Page-A-212x300.jpg" alt="Innovating Solutions: Micro-Nano Technologies and Sensors for Global Challenges &#8211; Research Summer School" ></p>
                            <p style="text-align: left"><strong>1 junio - 26 junio, 2026</strong></p>
                            <p><strong>Applications closed</strong></p>                        </div>

                        <a href="https://eunice-university.eu/es/course/micro-nano-technologies-and-sensor-global-challenges-research-summer-school/" class="box-link"></a>
                    </div>
                </div> 
            </div>
        </div>

            <div class="vc_col-sm-4 wpb_column column_container vc_column_container col no-extra-padding inherit_tablet inherit_phone" data-padding-pos="all" data-has-bg-color="false" data-bg-color="" data-bg-opacity="1" data-animation="" data-delay="0">
            <div class="vc_column-inner">
                <div class="wpb_wrapper">
                    <div class="nectar-fancy-box nectar-underline content-color-000000 aspect-1-1 past-deadline" data-style="image_above_text_underline" data-border-radius="none" data-animation="" data-delay="" data-alignment="left">
                        <div class="image-wrap">
                            <div class="box-bg">

                            </div>
                        </div>

                        <div class="text">
                            <h5>Strengthening resilience in the times of polycrises</h5>
                            <p><img loading="lazy" class="wp-image-7458 size-medium alignleft" src="https://eunice-university.eu/wp-content/uploads/2026/02/uva-resilience-bip-flyer-cover-212x300.jpg" alt="Strengthening resilience in the times of polycrises" ></p>
                            <p style="text-align: left"><strong>1 mayo - 29 mayo, 2026</strong></p>
                            <p><strong>Applications closed</strong></p>                        </div>

                        <a href="https://eunice-university.eu/es/course/strengthening-resilience-in-the-times-of-polycrises/" class="box-link"></a>
                    </div>
                </div> 
            </div>
        </div>

    </div><div class='row_col_wrap_12 col span_12 dark left'>        <div class="vc_col-sm-4 wpb_column column_container vc_column_container col no-extra-padding inherit_tablet inherit_phone" data-padding-pos="all" data-has-bg-color="false" data-bg-color="" data-bg-opacity="1" data-animation="" data-delay="0">
            <div class="vc_column-inner">
                <div class="wpb_wrapper">
                    <div class="nectar-fancy-box nectar-underline content-color-000000 aspect-1-1 past-deadline" data-style="image_above_text_underline" data-border-radius="none" data-animation="" data-delay="" data-alignment="left">
                        <div class="image-wrap">
                            <div class="box-bg">

                            </div>
                        </div>

                        <div class="text">
                            <h5>Systems and Transducers for Energy Harvesting from Renewables</h5>
                            <p><img loading="lazy" class="wp-image-7458 size-medium alignleft" src="https://eunice-university.eu/wp-content/uploads/2025/06/Systems-and-transducers-for-energy-harvesting-from-renewables-212x300.jpg" alt="Systems and Transducers for Energy Harvesting from Renewables" ></p>
                            <p style="text-align: left"><strong>10 octubre - 16 enero, 2026</strong></p>
                            <p><strong>Applications closed</strong></p>                        </div>

                        <a href="https://eunice-university.eu/es/course/systems-and-transducers-for-energy-harvesting-from-renewables/" class="box-link"></a>
                    </div>
                </div> 
            </div>
        </div>

            <div class="vc_col-sm-4 wpb_column column_container vc_column_container col no-extra-padding inherit_tablet inherit_phone" data-padding-pos="all" data-has-bg-color="false" data-bg-color="" data-bg-opacity="1" data-animation="" data-delay="0">
            <div class="vc_column-inner">
                <div class="wpb_wrapper">
                    <div class="nectar-fancy-box nectar-underline content-color-000000 aspect-1-1 past-deadline" data-style="image_above_text_underline" data-border-radius="none" data-animation="" data-delay="" data-alignment="left">
                        <div class="image-wrap">
                            <div class="box-bg">

                            </div>
                        </div>

                        <div class="text">
                            <h5>Applications of Artificial Intelligence &#8211; Summer School</h5>
                            <p><img loading="lazy" class="wp-image-7458 size-medium alignleft" src="https://eunice-university.eu/wp-content/uploads/2025/03/BIP-Summer-School_Applications-of-AI_Spain-212x300.jpg" alt="Applications of Artificial Intelligence &#8211; Summer School" ></p>
                            <p style="text-align: left"><strong>2 junio - 27 junio, 2025</strong></p>
                            <p><strong>Applications closed</strong></p>                        </div>

                        <a href="https://eunice-university.eu/es/course/applications-of-artificial-intelligence-summer-school/" class="box-link"></a>
                    </div>
                </div> 
            </div>
        </div>

    </div></div>            <div class="wpb_row vc_row-fluid vc_row">
                <div class="nectar-highlighted-text branch" data-style="full_text" data-exp="default" data-using-custom-color="false" data-animation-delay="false" data-color="" data-color-gradient="" style="">
                    <h3><strong>Engineering: Energy, Transport/Mobility</strong></h3>
                </div>
                <div class='row_col_wrap_12 col span_12 dark left'>        <div class="vc_col-sm-4 wpb_column column_container vc_column_container col no-extra-padding inherit_tablet inherit_phone" data-padding-pos="all" data-has-bg-color="false" data-bg-color="" data-bg-opacity="1" data-animation="" data-delay="0">
            <div class="vc_column-inner">
                <div class="wpb_wrapper">
                    <div class="nectar-fancy-box nectar-underline content-color-000000 aspect-1-1 past-deadline" data-style="image_above_text_underline" data-border-radius="none" data-animation="" data-delay="" data-alignment="left">
                        <div class="image-wrap">
                            <div class="box-bg">

                            </div>
                        </div>

                        <div class="text">
                            <h5>Cosmic Ray Physics 26-27 S1</h5>
                            <p><img loading="lazy" class="wp-image-7458 size-medium alignleft" src="https://eunice-university.eu/wp-content/uploads/2026/06/2026-COSMIC-RAY-PHYSICS--212x300.jpg" alt="Cosmic Ray Physics 26-27 S1" ></p>
                            <p style="text-align: left"><strong>5 octubre - 15 enero, 2027</strong></p>
                            <p><strong>Applications closed</strong></p>                        </div>

                        <a href="https://eunice-university.eu/es/course/cosmic-ray-physics-26-27-s1/" class="box-link"></a>
                    </div>
                </div> 
            </div>
        </div>

            <div class="vc_col-sm-4 wpb_column column_container vc_column_container col no-extra-padding inherit_tablet inherit_phone" data-padding-pos="all" data-has-bg-color="false" data-bg-color="" data-bg-opacity="1" data-animation="" data-delay="0">
            <div class="vc_column-inner">
                <div class="wpb_wrapper">
                    <div class="nectar-fancy-box nectar-underline content-color-000000 aspect-1-1 past-deadline" data-style="image_above_text_underline" data-border-radius="none" data-animation="" data-delay="" data-alignment="left">
                        <div class="image-wrap">
                            <div class="box-bg">

                            </div>
                        </div>

                        <div class="text">
                            <h5>Systems and Transducers for Energy Harvesting from Renewables</h5>
                            <p><img loading="lazy" class="wp-image-7458 size-medium alignleft" src="https://eunice-university.eu/wp-content/uploads/2025/06/Systems-and-transducers-for-energy-harvesting-from-renewables-212x300.jpg" alt="Systems and Transducers for Energy Harvesting from Renewables" ></p>
                            <p style="text-align: left"><strong>10 octubre - 16 enero, 2026</strong></p>
                            <p><strong>Applications closed</strong></p>                        </div>

                        <a href="https://eunice-university.eu/es/course/systems-and-transducers-for-energy-harvesting-from-renewables/" class="box-link"></a>
                    </div>
                </div> 
            </div>
        </div>

            <div class="vc_col-sm-4 wpb_column column_container vc_column_container col no-extra-padding inherit_tablet inherit_phone" data-padding-pos="all" data-has-bg-color="false" data-bg-color="" data-bg-opacity="1" data-animation="" data-delay="0">
            <div class="vc_column-inner">
                <div class="wpb_wrapper">
                    <div class="nectar-fancy-box nectar-underline content-color-000000 aspect-1-1 past-deadline" data-style="image_above_text_underline" data-border-radius="none" data-animation="" data-delay="" data-alignment="left">
                        <div class="image-wrap">
                            <div class="box-bg">

                            </div>
                        </div>

                        <div class="text">
                            <h5>Applications of Artificial Intelligence &#8211; Summer School</h5>
                            <p><img loading="lazy" class="wp-image-7458 size-medium alignleft" src="https://eunice-university.eu/wp-content/uploads/2025/03/BIP-Summer-School_Applications-of-AI_Spain-212x300.jpg" alt="Applications of Artificial Intelligence &#8211; Summer School" ></p>
                            <p style="text-align: left"><strong>2 junio - 27 junio, 2025</strong></p>
                            <p><strong>Applications closed</strong></p>                        </div>

                        <a href="https://eunice-university.eu/es/course/applications-of-artificial-intelligence-summer-school/" class="box-link"></a>
                    </div>
                </div> 
            </div>
        </div>

    </div></div>            <div class="wpb_row vc_row-fluid vc_row">
                <div class="nectar-highlighted-text branch" data-style="full_text" data-exp="default" data-using-custom-color="false" data-animation-delay="false" data-color="" data-color-gradient="" style="">
                    <h3><strong>Languages</strong></h3>
                </div>
                No content</div>            <div class="wpb_row vc_row-fluid vc_row">
                <div class="nectar-highlighted-text branch" data-style="full_text" data-exp="default" data-using-custom-color="false" data-animation-delay="false" data-color="" data-color-gradient="" style="">
                    <h3><strong>Information Technology (IT)</strong></h3>
                </div>
                <div class='row_col_wrap_12 col span_12 dark left'>        <div class="vc_col-sm-4 wpb_column column_container vc_column_container col no-extra-padding inherit_tablet inherit_phone" data-padding-pos="all" data-has-bg-color="false" data-bg-color="" data-bg-opacity="1" data-animation="" data-delay="0">
            <div class="vc_column-inner">
                <div class="wpb_wrapper">
                    <div class="nectar-fancy-box nectar-underline content-color-000000 aspect-1-1 past-deadline" data-style="image_above_text_underline" data-border-radius="none" data-animation="" data-delay="" data-alignment="left">
                        <div class="image-wrap">
                            <div class="box-bg">

                            </div>
                        </div>

                        <div class="text">
                            <h5>Network Security</h5>
                            <p><img loading="lazy" class="wp-image-7458 size-medium alignleft" src="https://eunice-university.eu/wp-content/uploads/2026/04/Network-Security-212x300.jpg" alt="Network Security" ></p>
                            <p style="text-align: left"><strong>6 julio - 10 julio, 2026</strong></p>
                            <p><strong>Applications closed</strong></p>                        </div>

                        <a href="https://eunice-university.eu/es/course/network-security/" class="box-link"></a>
                    </div>
                </div> 
            </div>
        </div>

            <div class="vc_col-sm-4 wpb_column column_container vc_column_container col no-extra-padding inherit_tablet inherit_phone" data-padding-pos="all" data-has-bg-color="false" data-bg-color="" data-bg-opacity="1" data-animation="" data-delay="0">
            <div class="vc_column-inner">
                <div class="wpb_wrapper">
                    <div class="nectar-fancy-box nectar-underline content-color-000000 aspect-1-1 past-deadline" data-style="image_above_text_underline" data-border-radius="none" data-animation="" data-delay="" data-alignment="left">
                        <div class="image-wrap">
                            <div class="box-bg">

                            </div>
                        </div>

                        <div class="text">
                            <h5>Innovating Solutions: Micro-Nano Technologies and Sensors for Global Challenges &#8211; Research Summer School</h5>
                            <p><img loading="lazy" class="wp-image-7458 size-medium alignleft" src="https://eunice-university.eu/wp-content/uploads/2026/02/Flyer-BIP-on-Micro-nano-Technologies-Page-A-212x300.jpg" alt="Innovating Solutions: Micro-Nano Technologies and Sensors for Global Challenges &#8211; Research Summer School" ></p>
                            <p style="text-align: left"><strong>1 junio - 26 junio, 2026</strong></p>
                            <p><strong>Applications closed</strong></p>                        </div>

                        <a href="https://eunice-university.eu/es/course/micro-nano-technologies-and-sensor-global-challenges-research-summer-school/" class="box-link"></a>
                    </div>
                </div> 
            </div>
        </div>

    </div></div></div>{"id":65179,"date":"2026-07-09T10:53:37","date_gmt":"2026-07-09T08:53:37","guid":{"rendered":"https:\/\/eunice-university.eu\/cursos\/programas-intensivos-semipresenciales\/"},"modified":"2026-08-10T10:13:42","modified_gmt":"2026-08-10T08:13:42","slug":"programas-intensivos-semipresenciales","status":"publish","type":"page","link":"https:\/\/eunice-university.eu\/es\/cursos\/programas-intensivos-semipresenciales\/","title":{"rendered":"Programas intensivos semipresenciales"},"content":{"rendered":"[vc_row type=\u00bbfull_width_background\u00bb full_screen_row_position=\u00bbmiddle\u00bb column_margin=\u00bbdefault\u00bb column_direction=\u00bbdefault\u00bb column_direction_tablet=\u00bbdefault\u00bb column_direction_phone=\u00bbdefault\u00bb bg_image=\u00bb64796&#8243; bg_image_type=\u00bbdefault\u00bb bg_position=\u00bbleft top\u00bb background_image_loading=\u00bbdefault\u00bb bg_repeat=\u00bbno-repeat\u00bb scene_position=\u00bbcenter\u00bb top_padding=\u00bb10%\u00bb bottom_padding=\u00bb10%\u00bb text_color=\u00bbdark\u00bb text_align=\u00bbleft\u00bb row_border_radius=\u00bbnone\u00bb row_border_radius_applies=\u00bbbg\u00bb row_position_desktop=\u00bbdefault\u00bb row_position_tablet=\u00bbinherit\u00bb row_position_phone=\u00bbinherit\u00bb overflow=\u00bbvisible\u00bb overlay_strength=\u00bb0.3&#8243; gradient_direction=\u00bbleft_to_right\u00bb shape_divider_position=\u00bbbottom\u00bb bg_image_animation=\u00bbnone\u00bb gradient_type=\u00bbdefault\u00bb shape_type=\u00bb\u00bb][vc_column column_padding=\u00bbno-extra-padding\u00bb column_padding_tablet=\u00bbinherit\u00bb column_padding_phone=\u00bbinherit\u00bb column_padding_position=\u00bball\u00bb flex_gap_desktop=\u00bb10px\u00bb column_element_direction_desktop=\u00bbdefault\u00bb column_element_spacing=\u00bbdefault\u00bb desktop_text_alignment=\u00bbdefault\u00bb tablet_text_alignment=\u00bbdefault\u00bb phone_text_alignment=\u00bbdefault\u00bb background_color_opacity=\u00bb1&#8243; background_hover_color_opacity=\u00bb1&#8243; column_backdrop_filter=\u00bbnone\u00bb column_shadow=\u00bbnone\u00bb column_border_radius=\u00bbnone\u00bb column_link_target=\u00bb_self\u00bb column_position=\u00bbdefault\u00bb gradient_direction=\u00bbleft_to_right\u00bb overlay_strength=\u00bb0.3&#8243; width=\u00bb1\/1&#8243; tablet_width_inherit=\u00bbdefault\u00bb animation_type=\u00bbdefault\u00bb bg_image_animation=\u00bbnone\u00bb border_type=\u00bbsimple\u00bb column_border_width=\u00bbnone\u00bb column_border_style=\u00bbsolid\u00bb][vc_column_text css=\u00bb\u00bb text_direction=\u00bbdefault\u00bb]\n<h1>Cursos intensivos semipresenciales<\/h1>\n[\/vc_column_text][\/vc_column][\/vc_row][vc_row type=\u00bbin_container\u00bb full_screen_row_position=\u00bbmiddle\u00bb column_margin=\u00bbdefault\u00bb column_direction=\u00bbdefault\u00bb column_direction_tablet=\u00bbdefault\u00bb column_direction_phone=\u00bbdefault\u00bb scene_position=\u00bbcenter\u00bb text_color=\u00bbdark\u00bb text_align=\u00bbleft\u00bb row_border_radius=\u00bbnone\u00bb row_border_radius_applies=\u00bbbg\u00bb row_position_desktop=\u00bbdefault\u00bb row_position_tablet=\u00bbinherit\u00bb row_position_phone=\u00bbinherit\u00bb overflow=\u00bbvisible\u00bb overlay_strength=\u00bb0.3&#8243; gradient_direction=\u00bbleft_to_right\u00bb shape_divider_position=\u00bbbottom\u00bb bg_image_animation=\u00bbnone\u00bb][vc_column column_padding=\u00bbno-extra-padding\u00bb column_padding_tablet=\u00bbinherit\u00bb column_padding_phone=\u00bbinherit\u00bb column_padding_position=\u00bball\u00bb flex_gap_desktop=\u00bb10px\u00bb column_element_direction_desktop=\u00bbdefault\u00bb column_element_spacing=\u00bbdefault\u00bb desktop_text_alignment=\u00bbdefault\u00bb tablet_text_alignment=\u00bbdefault\u00bb phone_text_alignment=\u00bbdefault\u00bb background_color_opacity=\u00bb1&#8243; background_hover_color_opacity=\u00bb1&#8243; column_backdrop_filter=\u00bbnone\u00bb column_shadow=\u00bbnone\u00bb column_border_radius=\u00bbnone\u00bb column_link_target=\u00bb_self\u00bb column_position=\u00bbdefault\u00bb gradient_direction=\u00bbleft_to_right\u00bb overlay_strength=\u00bb0.3&#8243; width=\u00bb1\/1&#8243; tablet_width_inherit=\u00bbdefault\u00bb animation_type=\u00bbdefault\u00bb bg_image_animation=\u00bbnone\u00bb border_type=\u00bbsimple\u00bb column_border_width=\u00bbnone\u00bb column_border_style=\u00bbsolid\u00bb][page_submenu alignment=\u00bbright\u00bb sticky=\u00bbtrue\u00bb bg_color=\u00bb#000000&#8243; link_color=\u00bb#ffffff\u00bb][page_link link_new_tab=\u00bbtrue\u00bb link_url=\u00bbhttps:\/\/eunice-university.eu\/courses\/courses-coordinators-contacts\/\u00bb title=\u00bbTu coordinador local\u00bb id=\u00bb1784547717583-5&#8243; tab_id=\u00bb1784547717584-5&#8243;] [\/page_link][page_link link_new_tab=\u00bbtrue\u00bb title=\u00bbCursos online\u00bb id=\u00bb1784547717601-4&#8243; tab_id=\u00bb1784547717601-5&#8243; link_url=\u00bbhttps:\/\/eunice-university.eu\/courses\/\u00bb][\/page_link][page_link title=\u00bbMOOCs\u00bb id=\u00bb1784547717612-5&#8243; tab_id=\u00bb1784547717612-2&#8243; link_url=\u00bbhttps:\/\/eunice-university.eu\/courses\/mooc-open-online-courses\/\u00bb][\/page_link][page_link title=\u00bbClubes estudiantiles\u00bb id=\u00bb1784547717623-9&#8243; tab_id=\u00bb1784547717623-0&#8243; link_url=\u00bb#C\u00bb][\/page_link][page_link link_new_tab=\u00bbtrue\u00bb title=\u00bbEmprendimiento\u00bb id=\u00bb1784547717633-8&#8243; tab_id=\u00bb1784547717633-9&#8243; link_url=\u00bbhttps:\/\/eunice-university.eu\/entrepreneurship\/\u00bb][\/page_link][page_link link_new_tab=\u00bbtrue\u00bb title=\u00bbPr\u00e1cticas\u00bb id=\u00bb1784547717644-3&#8243; tab_id=\u00bb1784547717644-10&#8243; link_url=\u00bbhttps:\/\/internships.eunice-university.eu\/\u00bb][\/page_link][page_link link_new_tab=\u00bbtrue\u00bb title=\u00bbEventos\u00bb id=\u00bb1784547717655-4&#8243; tab_id=\u00bb1784547717655-0&#8243; link_url=\u00bbhttps:\/\/eunice-university.eu\/category\/events\u00bb][\/page_link][page_link link_new_tab=\u00bbtrue\u00bb title=\u00bbM\u00e1steres\u00bb id=\u00bb1784547717665-9&#8243; tab_id=\u00bb1784547717666-7&#8243; link_url=\u00bbhttps:\/\/eunice-university.eu\/?page_id=44023&amp;preview=true\u00bb][\/page_link][page_link title=\u00bbBIP\u00bb id=\u00bb1784547717672-1&#8243; tab_id=\u00bb1784547717672-7&#8243; link_url=\u00bbhttps:\/\/eunice-university.eu\/courses\/blended-intensive-programmes\/\u00bb][\/page_link][page_link title=\u00bbMovilidad\u00bb id=\u00bb1784547717678-9&#8243; tab_id=\u00bb1784547717678-5&#8243; link_url=\u00bbhttps:\/\/eunice-university.eu\/erasmus-student-physical-mobility\/\u00bb][\/page_link][\/page_submenu][\/vc_column][\/vc_row][vc_row type=\u00bbin_container\u00bb full_screen_row_position=\u00bbmiddle\u00bb column_margin=\u00bbdefault\u00bb column_direction=\u00bbdefault\u00bb column_direction_tablet=\u00bbdefault\u00bb column_direction_phone=\u00bbdefault\u00bb scene_position=\u00bbcenter\u00bb top_padding=\u00bb5%\u00bb bottom_padding=\u00bb2%\u00bb left_padding_desktop=\u00bb3%\u00bb right_padding_desktop=\u00bb3%\u00bb text_color=\u00bbdark\u00bb text_align=\u00bbleft\u00bb row_border_radius=\u00bbnone\u00bb row_border_radius_applies=\u00bbbg\u00bb row_position_desktop=\u00bbdefault\u00bb row_position_tablet=\u00bbinherit\u00bb row_position_phone=\u00bbinherit\u00bb overflow=\u00bbvisible\u00bb overlay_strength=\u00bb0.3&#8243; gradient_direction=\u00bbleft_to_right\u00bb shape_divider_position=\u00bbbottom\u00bb bg_image_animation=\u00bbnone\u00bb gradient_type=\u00bbdefault\u00bb shape_type=\u00bb\u00bb][vc_column column_padding=\u00bbno-extra-padding\u00bb column_padding_tablet=\u00bbinherit\u00bb column_padding_phone=\u00bbinherit\u00bb column_padding_position=\u00bball\u00bb flex_gap_desktop=\u00bb10px\u00bb column_element_direction_desktop=\u00bbdefault\u00bb column_element_spacing=\u00bbdefault\u00bb desktop_text_alignment=\u00bbdefault\u00bb tablet_text_alignment=\u00bbdefault\u00bb phone_text_alignment=\u00bbdefault\u00bb background_color_opacity=\u00bb1&#8243; background_hover_color_opacity=\u00bb1&#8243; column_backdrop_filter=\u00bbnone\u00bb column_shadow=\u00bbnone\u00bb column_border_radius=\u00bbnone\u00bb column_link_target=\u00bb_self\u00bb column_position=\u00bbdefault\u00bb gradient_direction=\u00bbleft_to_right\u00bb overlay_strength=\u00bb0.3&#8243; width=\u00bb1\/1&#8243; tablet_width_inherit=\u00bbdefault\u00bb animation_type=\u00bbdefault\u00bb bg_image_animation=\u00bbnone\u00bb border_type=\u00bbsimple\u00bb column_border_width=\u00bbnone\u00bb column_border_style=\u00bbsolid\u00bb][vc_column_text css=\u00bb\u00bb text_direction=\u00bbdefault\u00bb]Los Programas Intensivos Combinados (BIP) son una <strong>experiencia de aprendizaje internacional innovadora<\/strong> que combina <strong>la colaboraci\u00f3n en l\u00ednea <\/strong>con una <strong>estancia presencial de corta duraci\u00f3n<\/strong> en una de las universidades miembro de EUNICE. Re\u00fanen a estudiantes y personal de diferentes pa\u00edses para trabajar en retos acad\u00e9micos comunes en un entorno aut\u00e9nticamente europeo. Este enfoque fomenta <strong>el intercambio intercultural<\/strong>, el aprendizaje colaborativo y el desarrollo de competencias tanto acad\u00e9micas como transversales.  <\/p>\n<blockquote><p>A diferencia de los programas de intercambio tradicionales, los BIP te permiten disfrutar de las ventajas de la movilidad internacional de una <strong>forma m\u00e1s flexible y accesible<\/strong>, combinando actividades de aprendizaje virtual con un componente presencial intensivo.<\/p><\/blockquote>\n<p>Elige un curso y solicita una <strong>beca<\/strong> de movilidad BIP en la Oficina Internacional de tu universidad.[\/vc_column_text][vc_row_inner column_margin=\u00bbdefault\u00bb column_direction=\u00bbdefault\u00bb column_direction_tablet=\u00bbdefault\u00bb column_direction_phone=\u00bbdefault\u00bb text_align=\u00bbcenter\u00bb row_position=\u00bbdefault\u00bb row_position_tablet=\u00bbinherit\u00bb row_position_phone=\u00bbinherit\u00bb overflow=\u00bbvisible\u00bb pointer_events=\u00bball\u00bb][vc_column_inner column_padding=\u00bbno-extra-padding\u00bb column_padding_tablet=\u00bbinherit\u00bb column_padding_phone=\u00bbinherit\u00bb column_padding_position=\u00bball\u00bb column_element_direction_desktop=\u00bbdefault\u00bb column_element_spacing=\u00bbdefault\u00bb centered_text=\u00bbtrue\u00bb desktop_text_alignment=\u00bbcenter\u00bb tablet_text_alignment=\u00bbdefault\u00bb phone_text_alignment=\u00bbdefault\u00bb background_color_opacity=\u00bb1&#8243; background_hover_color_opacity=\u00bb1&#8243; column_backdrop_filter=\u00bbnone\u00bb column_shadow=\u00bbnone\u00bb column_border_radius=\u00bbnone\u00bb column_link_target=\u00bb_self\u00bb overflow=\u00bbvisible\u00bb gradient_direction=\u00bbleft_to_right\u00bb overlay_strength=\u00bb0.3&#8243; width=\u00bb1\/1&#8243; tablet_width_inherit=\u00bbdefault\u00bb animation_type=\u00bbdefault\u00bb bg_image_animation=\u00bbnone\u00bb border_type=\u00bbsimple\u00bb column_border_width=\u00bbnone\u00bb column_border_style=\u00bbsolid\u00bb column_padding_type=\u00bbdefault\u00bb content_layout=\u00bbdefault\u00bb gradient_type=\u00bbdefault\u00bb][nectar_btn size=\u00bbjumbo\u00bb open_new_tab=\u00bbtrue\u00bb button_style=\u00bbregular\u00bb button_color_2=\u00bbAccent-Color\u00bb icon_family=\u00bbdefault_arrow\u00bb url=\u00bbhttps:\/\/eunice-university.eu\/erasmus-student-physical-mobility\/eunice-international-relations-offices-contacts\/\u00bb css_animation=\u00bbpulse\u00bb text=\u00bb\u00bfCu\u00e1l es el contacto de mi Oficina Internacional?\u00bb][\/vc_column_inner][\/vc_row_inner][vc_column_text css=\u00bb\u00bb text_direction=\u00bbdefault\u00bb]Los programas BIP est\u00e1n dise\u00f1ados y se imparten de forma conjunta por varias universidades de la red EUNICE, lo que ofrece a los participantes la oportunidad de trabajar con compa\u00f1eros y profesores de toda Europa, a la vez que obtienen <strong>reconocimiento acad\u00e9mico<\/strong> en forma de cr\u00e9ditos ECTS, siempre que lo permita la normativa de su universidad de origen.[\/vc_column_text][vc_column_text css=\u00bb\u00bb text_direction=\u00bbdefault\u00bb][\/vc_column_text][\/vc_column][\/vc_row]\n","protected":false},"excerpt":{"rendered":"<p>[vc_row type=\u00bbfull_width_background\u00bb full_screen_row_position=\u00bbmiddle\u00bb column_margin=\u00bbdefault\u00bb column_direction=\u00bbdefault\u00bb column_direction_tablet=\u00bbdefault\u00bb column_direction_phone=\u00bbdefault\u00bb bg_image=\u00bb64796&#8243; bg_image_type=\u00bbdefault\u00bb bg_position=\u00bbleft top\u00bb background_image_loading=\u00bbdefault\u00bb bg_repeat=\u00bbno-repeat\u00bb scene_position=\u00bbcenter\u00bb top_padding=\u00bb10%\u00bb bottom_padding=\u00bb10%\u00bb text_color=\u00bbdark\u00bb text_align=\u00bbleft\u00bb row_border_radius=\u00bbnone\u00bb row_border_radius_applies=\u00bbbg\u00bb row_position_desktop=\u00bbdefault\u00bb row_position_tablet=\u00bbinherit\u00bb row_position_phone=\u00bbinherit\u00bb overflow=\u00bbvisible\u00bb overlay_strength=\u00bb0.3&#8243;&#8230;<\/p>\n","protected":false},"author":14,"featured_media":0,"parent":52703,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"_uag_custom_page_level_css":"","footnotes":""},"class_list":["post-65179","page","type-page","status-publish"],"acf":[],"uagb_featured_image_src":{"full":false,"thumbnail":false,"medium":false,"medium_large":false,"large":false,"1536x1536":false,"2048x2048":false,"portfolio-thumb":false,"nectar_small_square":false,"portfolio-thumb_large":false,"portfolio-thumb_small":false,"portfolio-widget":false,"wide":false,"wide_photography":false,"wide_small":false,"regular":false,"regular_small":false,"tall":false,"wide_tall":false,"large_featured":false,"medium_featured":false},"uagb_author_info":{"display_name":"Ceballos Boyden, Lydia Ana","author_link":"https:\/\/eunice-university.eu\/es\/author\/8pyz8kqe93udy3fy\/"},"uagb_comment_info":0,"uagb_excerpt":"[vc_row type=\u00bbfull_width_background\u00bb full_screen_row_position=\u00bbmiddle\u00bb column_margin=\u00bbdefault\u00bb column_direction=\u00bbdefault\u00bb column_direction_tablet=\u00bbdefault\u00bb column_direction_phone=\u00bbdefault\u00bb bg_image=\u00bb64796&#8243; bg_image_type=\u00bbdefault\u00bb bg_position=\u00bbleft top\u00bb background_image_loading=\u00bbdefault\u00bb bg_repeat=\u00bbno-repeat\u00bb scene_position=\u00bbcenter\u00bb top_padding=\u00bb10%\u00bb bottom_padding=\u00bb10%\u00bb text_color=\u00bbdark\u00bb text_align=\u00bbleft\u00bb row_border_radius=\u00bbnone\u00bb row_border_radius_applies=\u00bbbg\u00bb row_position_desktop=\u00bbdefault\u00bb row_position_tablet=\u00bbinherit\u00bb row_position_phone=\u00bbinherit\u00bb overflow=\u00bbvisible\u00bb overlay_strength=\u00bb0.3&#8243;...","_links":{"self":[{"href":"https:\/\/eunice-university.eu\/es\/wp-json\/wp\/v2\/pages\/65179","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/eunice-university.eu\/es\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/eunice-university.eu\/es\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/eunice-university.eu\/es\/wp-json\/wp\/v2\/users\/14"}],"replies":[{"embeddable":true,"href":"https:\/\/eunice-university.eu\/es\/wp-json\/wp\/v2\/comments?post=65179"}],"version-history":[{"count":2,"href":"https:\/\/eunice-university.eu\/es\/wp-json\/wp\/v2\/pages\/65179\/revisions"}],"predecessor-version":[{"id":65182,"href":"https:\/\/eunice-university.eu\/es\/wp-json\/wp\/v2\/pages\/65179\/revisions\/65182"}],"up":[{"embeddable":true,"href":"https:\/\/eunice-university.eu\/es\/wp-json\/wp\/v2\/pages\/52703"}],"wp:attachment":[{"href":"https:\/\/eunice-university.eu\/es\/wp-json\/wp\/v2\/media?parent=65179"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}